{"id":6151,"date":"2023-10-01T09:20:33","date_gmt":"2023-10-01T09:20:33","guid":{"rendered":"https:\/\/piese-serviceprintere.ro\/index.php\/product\/q6687-67001-spindle-assembly-hp-designjet-t610-t770-t790-t1100-t1200-t1300-t2300-44-inch\/"},"modified":"2023-10-01T09:20:35","modified_gmt":"2023-10-01T09:20:35","slug":"q6687-67001-spindle-assembly-hp-designjet-t610-t770-t790-t1100-t1200-t1300-t2300-44-inch","status":"publish","type":"product","link":"https:\/\/piese-serviceprintere.ro\/index.php\/product\/q6687-67001-spindle-assembly-hp-designjet-t610-t770-t790-t1100-t1200-t1300-t2300-44-inch\/","title":{"rendered":"Q6687-67001 Spindle assembly HP DesignJet T610 T770 T790 T1100 T1200 T1300 T2300 44-inch"},"content":{"rendered":"<p>Q6687-67001 Spindle assembly HP DesignJet T610 T770 T790 T1100 T1200 T1300 T2300 44-inch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Q6687-67001 Spindle assembly HP DesignJet T610 T770 T790 T1100 T1200 T1300 T2300 44-inch<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_cat":[15],"product_tag":[],"class_list":["post-6151","product","type-product","status-publish","hentry","product_cat-uncategorized"],"_links":{"self":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product\/6151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/comments?post=6151"}],"wp:attachment":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/media?parent=6151"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product_cat?post=6151"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product_tag?post=6151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}