{"id":6802,"date":"2023-10-01T09:22:22","date_gmt":"2023-10-01T09:22:22","guid":{"rendered":"https:\/\/piese-serviceprintere.ro\/index.php\/product\/115r00089-xerox-versalink-c405c400workcentre-6655-genuine-220v-fuser-unit\/"},"modified":"2023-10-01T09:22:22","modified_gmt":"2023-10-01T09:22:22","slug":"115r00089-xerox-versalink-c405c400workcentre-6655-genuine-220v-fuser-unit","status":"publish","type":"product","link":"https:\/\/piese-serviceprintere.ro\/index.php\/product\/115r00089-xerox-versalink-c405c400workcentre-6655-genuine-220v-fuser-unit\/","title":{"rendered":"115R00089 Xerox VersaLink C405,C400,WorkCentre 6655 Genuine 220V Fuser Unit"},"content":{"rendered":"<p>115R00089 Xerox VersaLink C405,C400,WorkCentre 6655 Genuine 220V Fuser Unit<\/p>\n","protected":false},"excerpt":{"rendered":"<p>115R00089 Xerox VersaLink C405,C400,WorkCentre 6655 Genuine 220V Fuser Unit<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_cat":[15],"product_tag":[],"class_list":["post-6802","product","type-product","status-publish","hentry","product_cat-uncategorized"],"_links":{"self":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product\/6802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/comments?post=6802"}],"wp:attachment":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/media?parent=6802"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product_cat?post=6802"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product_tag?post=6802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}