{"id":6884,"date":"2023-10-01T09:22:36","date_gmt":"2023-10-01T09:22:36","guid":{"rendered":"https:\/\/piese-serviceprintere.ro\/index.php\/product\/604k62220-fuser-unit-220v-workcentre-7525-7530-7535-7830\/"},"modified":"2023-10-01T09:22:36","modified_gmt":"2023-10-01T09:22:36","slug":"604k62220-fuser-unit-220v-workcentre-7525-7530-7535-7830","status":"publish","type":"product","link":"https:\/\/piese-serviceprintere.ro\/index.php\/product\/604k62220-fuser-unit-220v-workcentre-7525-7530-7535-7830\/","title":{"rendered":"604K62220 Fuser Unit 220v, WorkCentre 7525, 7530, 7535, 7830"},"content":{"rendered":"<p>604K62220 Fuser Unit 220v, WorkCentre 7525, 7530, 7535, 7830<\/p>\n","protected":false},"excerpt":{"rendered":"<p>604K62220 Fuser Unit 220v, WorkCentre 7525, 7530, 7535, 7830<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_cat":[15],"product_tag":[],"class_list":["post-6884","product","type-product","status-publish","hentry","product_cat-uncategorized"],"_links":{"self":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product\/6884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/comments?post=6884"}],"wp:attachment":[{"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/media?parent=6884"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product_cat?post=6884"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piese-serviceprintere.ro\/index.php\/wp-json\/wp\/v2\/product_tag?post=6884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}